{"id":4573,"date":"2019-05-14T10:50:47","date_gmt":"2019-05-14T08:50:47","guid":{"rendered":"http:\/\/zl31wzsmw.preview.infomaniak.website\/?p=4573"},"modified":"2019-05-16T14:24:04","modified_gmt":"2019-05-16T12:24:04","slug":"mallette-logement-energie-pour-des-animations-sur-le-theme-de-lenergie-pratiques-et-pedagogiques","status":"publish","type":"post","link":"https:\/\/www.socialenergie.be\/fr\/mallette-logement-energie-pour-des-animations-sur-le-theme-de-lenergie-pratiques-et-pedagogiques\/","title":{"rendered":"Mallette Logement &#038; Energie : pour des animations sur le th\u00e8me de l&rsquo;\u00e9nergie pratiques et p\u00e9dagogiques"},"content":{"rendered":"<p><strong>Vous souhaitez organiser des animations sur le th\u00e8me de l\u2019\u00e9nergie ? Ou expliquer de mani\u00e8re p\u00e9dagogique une facture, un d\u00e9compte de charges ou encore un des enjeux de la pr\u00e9carit\u00e9 \u00e9nerg\u00e9tique ?<\/strong><\/p>\n<p>L&rsquo;ASBL Lire et Ecrire, en collaboration avec le CASE et Energie Info Wallonie, vient de compl\u00e9ter le contenu de sa <strong>mallette p\u00e9dagogique Logement<\/strong> (de la collection \u00ab Bienvenue en Belgique \u00bb) en y int\u00e9grant des animations \u00ab \u00e9nergie \u00bb. La mallette est adapt\u00e9e pour un public de primo arrivants &#8211; particuli\u00e8rement les primo arrivants analphab\u00e8tes ou peu scolaris\u00e9s &#8211; mais peut tout \u00e0 fait convenir \u00e0 un public plus scolaris\u00e9.<\/p>\n<p>La mallette reprend <strong>6 th\u00e9matiques<\/strong> : le march\u00e9 de l\u2019\u00e9nergie (\u00ab\u00a0Energic\u2019\u00e0 brac\u00a0\u00bb), le d\u00e9marchage, le choix du fournisseur, la facture d\u2019\u00e9nergie, les d\u00e9comptes de charges et les recours possibles en cas de non-paiement (\u00ab\u00a0Je n\u2019arrive pas \u00e0 payer\u00a0\u00bb). Elle permet d\u2019appr\u00e9hender ces th\u00e8mes de mani\u00e8re pratique et p\u00e9dagogique.<\/p>\n<p>Sur le site, vous trouverez la pr\u00e9sentation de la <a href=\"http:\/\/www.lire-et-ecrire.be\/Logement\" target=\"_blank\" rel=\"noopener noreferrer\" target=\"_blank\" rel=\"noopener noreferrer\">mallette logement<\/a> ainsi que des <a href=\"http:\/\/www.lire-et-ecrire.be\/Animations-pour-la-mallette-pedagogique-Logement\" target=\"_blank\" rel=\"noopener noreferrer\" target=\"_blank\" rel=\"noopener noreferrer\">animations \u00e9nergie<\/a>.<\/p>\n<p class=\"cadre\">Pour les d\u00e9couvrir, Lire et Ecrire propose <strong>quatre journ\u00e9es de pr\u00e9sentation<\/strong>,\u00a0dont une le 02 juillet \u00e0 Bruxelles. Le matin aura lieu la pr\u00e9sentation de la mallette Logement, avec les animations \u00e9nergie, et l\u2019apr\u00e8s-midi la mallette Enseignement. Pour en savoir plus (d\u00e9roulement de la journ\u00e9e, frais, \u2026) et vous inscrire,\u00a0 c\u2019est par <a href=\"http:\/\/www.lire-et-ecrire.be\/Presentation-des-animations-Enseignement-et-Logement-14614\" target=\"_blank\" rel=\"noopener noreferrer\" target=\"_blank\" rel=\"noopener noreferrer\">ici<\/a>\u00a0!<br \/>\nSi vous \u00eates int\u00e9ress\u00e9s, vous pouvez consulter et\/ou emprunter gratuitement la mallette des six animations \u00e9nergie aupr\u00e8s de nos services : <a href=\"mailto:socialenergie@fdss.be\">socialenergie@fdss.be<\/a>.<br \/>\nEt pour en savoir plus sur les mallettes de Lire et Ecrire, c\u2019est par <a href=\"http:\/\/www.lire-et-ecrire.be\/Bienvenue-en-Belgique-Neuf-mallettes-pedagogiques\" target=\"_blank\" rel=\"noopener noreferrer\" target=\"_blank\" rel=\"noopener noreferrer\">l\u00e0<\/a>!<\/p>\n<p><a href=\"https:\/\/www.socialenergie.be\/wp-content\/uploads\/DSC_0486.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-4584\" src=\"https:\/\/www.socialenergie.be\/wp-content\/uploads\/DSC_0486-1024x683.jpg\" alt=\"\" width=\"1024\" height=\"683\" srcset=\"https:\/\/www.socialenergie.be\/wp-content\/uploads\/DSC_0486-1024x683.jpg 1024w, https:\/\/www.socialenergie.be\/wp-content\/uploads\/DSC_0486-1536x1024.jpg 1536w, https:\/\/www.socialenergie.be\/wp-content\/uploads\/DSC_0486-2048x1365.jpg 2048w, https:\/\/www.socialenergie.be\/wp-content\/uploads\/DSC_0486-150x100.jpg 150w, https:\/\/www.socialenergie.be\/wp-content\/uploads\/DSC_0486-300x200.jpg 300w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vous souhaitez organiser des animations sur le th\u00e8me de l\u2019\u00e9nergie ? Ou expliquer de mani\u00e8re p\u00e9dagogique une facture, un d\u00e9compte de charges ou encore un des enjeux de la pr\u00e9carit\u00e9 \u00e9nerg\u00e9tique ? L&rsquo;ASBL Lire et Ecrire, en collaboration avec le CASE et Energie Info Wallonie, vient de compl\u00e9ter le contenu de sa mallette p\u00e9dagogique Logement [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4573","post","type-post","status-publish","format-standard","hentry","category-actualites"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.socialenergie.be\/fr\/wp-json\/wp\/v2\/posts\/4573","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.socialenergie.be\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.socialenergie.be\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.socialenergie.be\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.socialenergie.be\/fr\/wp-json\/wp\/v2\/comments?post=4573"}],"version-history":[{"count":10,"href":"https:\/\/www.socialenergie.be\/fr\/wp-json\/wp\/v2\/posts\/4573\/revisions"}],"predecessor-version":[{"id":4636,"href":"https:\/\/www.socialenergie.be\/fr\/wp-json\/wp\/v2\/posts\/4573\/revisions\/4636"}],"wp:attachment":[{"href":"https:\/\/www.socialenergie.be\/fr\/wp-json\/wp\/v2\/media?parent=4573"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.socialenergie.be\/fr\/wp-json\/wp\/v2\/categories?post=4573"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.socialenergie.be\/fr\/wp-json\/wp\/v2\/tags?post=4573"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}